{"id":10862,"date":"2025-09-10T13:47:51","date_gmt":"2025-09-10T09:47:51","guid":{"rendered":"https:\/\/eternos974.live\/?p=10862"},"modified":"2025-09-10T13:47:51","modified_gmt":"2025-09-10T09:47:51","slug":"avant-la-sortie-de-gta-6-partez-a-la-decouverte-de-gta-v-sur-ps5-il-est-a-moins-de-20e-pendant-encore-quelques-jours","status":"publish","type":"post","link":"https:\/\/eternos974.live\/index.php\/2025\/09\/10\/avant-la-sortie-de-gta-6-partez-a-la-decouverte-de-gta-v-sur-ps5-il-est-a-moins-de-20e-pendant-encore-quelques-jours\/","title":{"rendered":"Avant la sortie de GTA 6, partez \u00e0 la d\u00e9couverte de GTA V sur PS5 : il est \u00e0 moins de 20\u20ac pendant encore quelques jours !"},"content":{"rendered":"<p>\u00c0 quelques mois de la sortie de <b>GTA 6<\/b>, GTA V est propos\u00e9 \u00e0 moins de 20\u20ac sur PS5. Parfait pour decouvrir ou red\u00e9couvrir ce classique du jeu vid\u00e9o avant l&rsquo;arriv\u00e9e du prochain opus. <a href='https:\/\/www.jeuxvideo.com\/news\/2025298\/avant-la-sortie-de-gta-6-partez-a-la-decouverte-de-gta-v-sur-ps5-il-est-a-moins-de-20-pendant-encore-quelques-jours.htm'>En savoir plus<\/a><\/p>\n<p><img data-recalc-dims=\"1\" src=\"https:\/\/i0.wp.com\/image.jeuxvideo.com\/medias-lg\/175699\/1756987632-7202-card.jpg?w=1140&#038;ssl=1\" alt='GTA V PS5'><\/p>\n<p><i> #GrandTheftAuto #GTAV #PS5 <\/i><\/p>\n<p><\/p>\n<hr>\n<p><a href=\"https:\/\/eternos974.live\/index.php\/2025\/08\/16\/tavern-master-la-gestion-medievale-en-mousse-et-en-folie\/\">\ud83d\udd34 Retrouvez notre dernier article : Tavern Master \u2013 La gestion m\u00e9di\u00e9vale en mousse et en folie<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 quelques mois de la sortie de GTA 6, GTA V est propos\u00e9 \u00e0 moins de 20\u20ac sur PS5. Parfait&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"_crdt_document":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"cybocfi_hide_featured_image":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[43,20],"tags":[44],"class_list":["post-10862","post","type-post","status-publish","format-aside","hentry","category-breve","category-news","tag-breve","post_format-post-format-aside"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts\/10862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/comments?post=10862"}],"version-history":[{"count":1,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts\/10862\/revisions"}],"predecessor-version":[{"id":10866,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts\/10862\/revisions\/10866"}],"wp:attachment":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/media?parent=10862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/categories?post=10862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/tags?post=10862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}