{"id":14210,"date":"2026-01-23T13:35:31","date_gmt":"2026-01-23T09:35:31","guid":{"rendered":"https:\/\/eternos974.live\/?p=14210"},"modified":"2026-01-23T13:35:31","modified_gmt":"2026-01-23T09:35:31","slug":"cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich","status":"publish","type":"post","link":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/","title":{"rendered":"Cet acteur a prononc\u00e9 l\u2019une des phrases les plus cultes de Fallout et tout ce qu\u2019il a re\u00e7u, c\u2019est \u201c40 dollars et un sandwich\u201d"},"content":{"rendered":"<p>Un grand acteur a pr\u00eat\u00e9 sa voix pour une phrase culte de Fallout pour une r\u00e9mun\u00e9ration de seulement 40 dollars et un sandwich. Cette m\u00eame actrice qui avait fait ses d\u00e9buts en 1997 dans la version PC de Magic : The Gathering, refait parler d&rsquo;elle. <a href=\"https:\/\/www.jeuxvideo.com\/news\/2057406\/cet-acteur-a-prononce-l-une-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-qu-il-a-recu-c-est-40-dollars-et-un-sandwich.htm\">Lire la suite<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/image.jeuxvideo.com\/medias-lg\/176858\/1768581411-4191-card.jpg?w=1140&#038;ssl=1\" alt=\"Fallout actor paid in sandwich\"><\/p>\n<p>#Fallout #VoiceActing #GamingNews<\/p>\n<p><\/p>\n<hr>\n<p><a href=\"https:\/\/eternos974.live\/index.php\/2025\/12\/01\/%f0%9f%8e%84-concours-de-noel-2025-gagnez-des-cles-steam-dont-clair-obscur-expedition-33-%f0%9f%8e%81\/\">\ud83d\udd34 Retrouvez notre dernier article : \ud83c\udf84 Concours de No\u00ebl 2025 : Gagnez des cl\u00e9s STEAM, dont Clair Obscur \u2013 Exp\u00e9dition 33 ! \ud83c\udf81<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grand acteur a pr\u00eat\u00e9 sa voix pour une phrase culte de Fallout pour une r\u00e9mun\u00e9ration de seulement 40 dollars&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"_monsterinsights_skip_tracking":false,"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[43,20],"tags":[44],"class_list":["post-14210","post","type-post","status-publish","format-aside","hentry","category-breve","category-news","tag-breve","post_format-post-format-aside"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Un grand acteur a pr\u00eat\u00e9 sa voix pour une phrase culte de Fallout pour une r\u00e9mun\u00e9ration de seulement 40 dollars et un sandwich. Cette m\u00eame actrice qui avait fait ses d\u00e9buts en 1997 dans la version PC de Magic : The Gathering, refait parler d&#039;elle. Lire la suite #Fallout #VoiceActing #GamingNews \ud83d\udd34 Retrouvez notre dernier\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"eternos974\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"L&#039;EternoStation - LIVE, CHILL &amp; FUN\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Cet acteur a prononc\u00e9 l\u2019une des phrases les plus cultes de Fallout et tout ce qu\u2019il a re\u00e7u, c\u2019est \u201c40 dollars et un sandwich\u201d - L&#039;EternoStation\" \/>\n\t\t<meta property=\"og:description\" content=\"Un grand acteur a pr\u00eat\u00e9 sa voix pour une phrase culte de Fallout pour une r\u00e9mun\u00e9ration de seulement 40 dollars et un sandwich. Cette m\u00eame actrice qui avait fait ses d\u00e9buts en 1997 dans la version PC de Magic : The Gathering, refait parler d&#039;elle. Lire la suite #Fallout #VoiceActing #GamingNews \ud83d\udd34 Retrouvez notre dernier\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-01-23T09:35:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-01-23T09:35:31+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Cet acteur a prononc\u00e9 l\u2019une des phrases les plus cultes de Fallout et tout ce qu\u2019il a re\u00e7u, c\u2019est \u201c40 dollars et un sandwich\u201d - L&#039;EternoStation\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Un grand acteur a pr\u00eat\u00e9 sa voix pour une phrase culte de Fallout pour une r\u00e9mun\u00e9ration de seulement 40 dollars et un sandwich. Cette m\u00eame actrice qui avait fait ses d\u00e9buts en 1997 dans la version PC de Magic : The Gathering, refait parler d&#039;elle. Lire la suite #Fallout #VoiceActing #GamingNews \ud83d\udd34 Retrouvez notre dernier\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2026\\\/01\\\/23\\\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\\\/#blogposting\",\"name\":\"Cet acteur a prononc\\u00e9 l\\u2019une des phrases les plus cultes de Fallout et tout ce qu\\u2019il a re\\u00e7u, c\\u2019est \\u201c40 dollars et un sandwich\\u201d - L'EternoStation\",\"headline\":\"Cet acteur a prononc\\u00e9 l\\u2019une des phrases les plus cultes de Fallout et tout ce qu\\u2019il a re\\u00e7u, c\\u2019est \\u201c40 dollars et un sandwich\\u201d\",\"author\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/image.jeuxvideo.com\\\/medias-lg\\\/176858\\\/1768581411-4191-card.jpg\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2026\\\/01\\\/23\\\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\\\/#articleImage\"},\"datePublished\":\"2026-01-23T13:35:31+04:00\",\"dateModified\":\"2026-01-23T13:35:31+04:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2026\\\/01\\\/23\\\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2026\\\/01\\\/23\\\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\\\/#webpage\"},\"articleSection\":\"br\\u00e8ve, news, br\\u00e8ve, En passant\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2026\\\/01\\\/23\\\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live#listItem\",\"position\":1,\"name\":\"Domicile\",\"item\":\"https:\\\/\\\/eternos974.live\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"news\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"news\",\"item\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/breve\\\/#listItem\",\"name\":\"br\\u00e8ve\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live#listItem\",\"name\":\"Domicile\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/breve\\\/#listItem\",\"position\":3,\"name\":\"br\\u00e8ve\",\"item\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/breve\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2026\\\/01\\\/23\\\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\\\/#listItem\",\"name\":\"Cet acteur a prononc\\u00e9 l\\u2019une des phrases les plus cultes de Fallout et tout ce qu\\u2019il a re\\u00e7u, c\\u2019est \\u201c40 dollars et un sandwich\\u201d\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"news\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2026\\\/01\\\/23\\\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\\\/#listItem\",\"position\":4,\"name\":\"Cet acteur a prononc\\u00e9 l\\u2019une des phrases les plus cultes de Fallout et tout ce qu\\u2019il a re\\u00e7u, c\\u2019est \\u201c40 dollars et un sandwich\\u201d\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/breve\\\/#listItem\",\"name\":\"br\\u00e8ve\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/#organization\",\"name\":\"L'EternoStation\",\"description\":\"LIVE, CHILL & FUN\",\"url\":\"https:\\\/\\\/eternos974.live\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/#author\",\"url\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/\",\"name\":\"eternos974\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2026\\\/01\\\/23\\\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7141af684a779babd9913ea86616250a147cbdf2bd354aa007f434fc4dc1aff?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"eternos974\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2026\\\/01\\\/23\\\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\\\/#webpage\",\"url\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2026\\\/01\\\/23\\\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\\\/\",\"name\":\"Cet acteur a prononc\\u00e9 l\\u2019une des phrases les plus cultes de Fallout et tout ce qu\\u2019il a re\\u00e7u, c\\u2019est \\u201c40 dollars et un sandwich\\u201d - L'EternoStation\",\"description\":\"Un grand acteur a pr\\u00eat\\u00e9 sa voix pour une phrase culte de Fallout pour une r\\u00e9mun\\u00e9ration de seulement 40 dollars et un sandwich. Cette m\\u00eame actrice qui avait fait ses d\\u00e9buts en 1997 dans la version PC de Magic : The Gathering, refait parler d'elle. Lire la suite #Fallout #VoiceActing #GamingNews \\ud83d\\udd34 Retrouvez notre dernier\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2026\\\/01\\\/23\\\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/#author\"},\"datePublished\":\"2026-01-23T13:35:31+04:00\",\"dateModified\":\"2026-01-23T13:35:31+04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/#website\",\"url\":\"https:\\\/\\\/eternos974.live\\\/\",\"name\":\"L'EternoStation\",\"description\":\"LIVE, CHILL & FUN\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Cet acteur a prononc\u00e9 l\u2019une des phrases les plus cultes de Fallout et tout ce qu\u2019il a re\u00e7u, c\u2019est \u201c40 dollars et un sandwich\u201d - L'EternoStation","description":"Un grand acteur a pr\u00eat\u00e9 sa voix pour une phrase culte de Fallout pour une r\u00e9mun\u00e9ration de seulement 40 dollars et un sandwich. Cette m\u00eame actrice qui avait fait ses d\u00e9buts en 1997 dans la version PC de Magic : The Gathering, refait parler d'elle. Lire la suite #Fallout #VoiceActing #GamingNews \ud83d\udd34 Retrouvez notre dernier","canonical_url":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/#blogposting","name":"Cet acteur a prononc\u00e9 l\u2019une des phrases les plus cultes de Fallout et tout ce qu\u2019il a re\u00e7u, c\u2019est \u201c40 dollars et un sandwich\u201d - L'EternoStation","headline":"Cet acteur a prononc\u00e9 l\u2019une des phrases les plus cultes de Fallout et tout ce qu\u2019il a re\u00e7u, c\u2019est \u201c40 dollars et un sandwich\u201d","author":{"@id":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/#author"},"publisher":{"@id":"https:\/\/eternos974.live\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/image.jeuxvideo.com\/medias-lg\/176858\/1768581411-4191-card.jpg","@id":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/#articleImage"},"datePublished":"2026-01-23T13:35:31+04:00","dateModified":"2026-01-23T13:35:31+04:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/#webpage"},"isPartOf":{"@id":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/#webpage"},"articleSection":"br\u00e8ve, news, br\u00e8ve, En passant"},{"@type":"BreadcrumbList","@id":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eternos974.live#listItem","position":1,"name":"Domicile","item":"https:\/\/eternos974.live","nextItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/#listItem","name":"news"}},{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/#listItem","position":2,"name":"news","item":"https:\/\/eternos974.live\/index.php\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/#listItem","name":"br\u00e8ve"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live#listItem","name":"Domicile"}},{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/#listItem","position":3,"name":"br\u00e8ve","item":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/#listItem","name":"Cet acteur a prononc\u00e9 l\u2019une des phrases les plus cultes de Fallout et tout ce qu\u2019il a re\u00e7u, c\u2019est \u201c40 dollars et un sandwich\u201d"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/#listItem","name":"news"}},{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/#listItem","position":4,"name":"Cet acteur a prononc\u00e9 l\u2019une des phrases les plus cultes de Fallout et tout ce qu\u2019il a re\u00e7u, c\u2019est \u201c40 dollars et un sandwich\u201d","previousItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/#listItem","name":"br\u00e8ve"}}]},{"@type":"Organization","@id":"https:\/\/eternos974.live\/#organization","name":"L'EternoStation","description":"LIVE, CHILL & FUN","url":"https:\/\/eternos974.live\/"},{"@type":"Person","@id":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/#author","url":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/","name":"eternos974","image":{"@type":"ImageObject","@id":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f7141af684a779babd9913ea86616250a147cbdf2bd354aa007f434fc4dc1aff?s=96&d=mm&r=g","width":96,"height":96,"caption":"eternos974"}},{"@type":"WebPage","@id":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/#webpage","url":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/","name":"Cet acteur a prononc\u00e9 l\u2019une des phrases les plus cultes de Fallout et tout ce qu\u2019il a re\u00e7u, c\u2019est \u201c40 dollars et un sandwich\u201d - L'EternoStation","description":"Un grand acteur a pr\u00eat\u00e9 sa voix pour une phrase culte de Fallout pour une r\u00e9mun\u00e9ration de seulement 40 dollars et un sandwich. Cette m\u00eame actrice qui avait fait ses d\u00e9buts en 1997 dans la version PC de Magic : The Gathering, refait parler d'elle. Lire la suite #Fallout #VoiceActing #GamingNews \ud83d\udd34 Retrouvez notre dernier","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/eternos974.live\/#website"},"breadcrumb":{"@id":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/#breadcrumblist"},"author":{"@id":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/#author"},"creator":{"@id":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/#author"},"datePublished":"2026-01-23T13:35:31+04:00","dateModified":"2026-01-23T13:35:31+04:00"},{"@type":"WebSite","@id":"https:\/\/eternos974.live\/#website","url":"https:\/\/eternos974.live\/","name":"L'EternoStation","description":"LIVE, CHILL & FUN","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/eternos974.live\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"L'EternoStation - LIVE, CHILL &amp; FUN","og:type":"article","og:title":"Cet acteur a prononc\u00e9 l\u2019une des phrases les plus cultes de Fallout et tout ce qu\u2019il a re\u00e7u, c\u2019est \u201c40 dollars et un sandwich\u201d - L'EternoStation","og:description":"Un grand acteur a pr\u00eat\u00e9 sa voix pour une phrase culte de Fallout pour une r\u00e9mun\u00e9ration de seulement 40 dollars et un sandwich. Cette m\u00eame actrice qui avait fait ses d\u00e9buts en 1997 dans la version PC de Magic : The Gathering, refait parler d'elle. Lire la suite #Fallout #VoiceActing #GamingNews \ud83d\udd34 Retrouvez notre dernier","og:url":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/","article:published_time":"2026-01-23T09:35:31+00:00","article:modified_time":"2026-01-23T09:35:31+00:00","twitter:card":"summary_large_image","twitter:title":"Cet acteur a prononc\u00e9 l\u2019une des phrases les plus cultes de Fallout et tout ce qu\u2019il a re\u00e7u, c\u2019est \u201c40 dollars et un sandwich\u201d - L'EternoStation","twitter:description":"Un grand acteur a pr\u00eat\u00e9 sa voix pour une phrase culte de Fallout pour une r\u00e9mun\u00e9ration de seulement 40 dollars et un sandwich. Cette m\u00eame actrice qui avait fait ses d\u00e9buts en 1997 dans la version PC de Magic : The Gathering, refait parler d'elle. Lire la suite #Fallout #VoiceActing #GamingNews \ud83d\udd34 Retrouvez notre dernier"},"aioseo_meta_data":{"post_id":"14210","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-01-23 09:47:09","updated":"2026-01-23 09:47:09","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eternos974.live\" title=\"Domicile\">Domicile<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eternos974.live\/index.php\/category\/news\/\" title=\"news\">news<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/\" title=\"br\u00e8ve\">br\u00e8ve<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCet acteur a prononc\u00e9 l\u2019une des phrases les plus cultes de Fallout et tout ce qu\u2019il a re\u00e7u, c\u2019est \u201c40 dollars et un sandwich\u201d\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Domicile","link":"https:\/\/eternos974.live"},{"label":"news","link":"https:\/\/eternos974.live\/index.php\/category\/news\/"},{"label":"br\u00e8ve","link":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/"},{"label":"Cet acteur a prononc\u00e9 l\u2019une des phrases les plus cultes de Fallout et tout ce qu\u2019il a re\u00e7u, c\u2019est \u201c40 dollars et un sandwich\u201d","link":"https:\/\/eternos974.live\/index.php\/2026\/01\/23\/cet-acteur-a-prononce-lune-des-phrases-les-plus-cultes-de-fallout-et-tout-ce-quil-a-recu-cest-40-dollars-et-un-sandwich\/"}],"jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts\/14210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/comments?post=14210"}],"version-history":[{"count":1,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts\/14210\/revisions"}],"predecessor-version":[{"id":14214,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts\/14210\/revisions\/14214"}],"wp:attachment":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/media?parent=14210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/categories?post=14210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/tags?post=14210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}