{"id":5246,"date":"2025-03-22T22:02:56","date_gmt":"2025-03-22T18:02:56","guid":{"rendered":"https:\/\/eternos974.live\/?p=5246"},"modified":"2025-03-22T22:02:56","modified_gmt":"2025-03-22T18:02:56","slug":"28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne","status":"publish","type":"post","link":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/","title":{"rendered":"28 ans apr\u00e8s, ce jeu vid\u00e9o PlayStation compar\u00e9 \u00e0 l&rsquo;un des meilleurs de tous les temps revient dans une version ultra moderne&#8230;"},"content":{"rendered":"<p>Le l\u00e9gendaire jeu vid\u00e9o de PlayStation, Croc, consid\u00e9r\u00e9 comme l&rsquo;un des meilleurs de tous les temps, fait un retour remarqu\u00e9 apr\u00e8s 28 ans. Cette r\u00e9\u00e9dition du c\u00e9l\u00e8bre jeu des ann\u00e9es 90 s&rsquo;accompagne d&rsquo;une version ultra moderne, d&rsquo;une date de sortie et d&rsquo;un trailer in\u00e9dits. <a href=\"https:\/\/www.jeuxvideo.com\/news\/1980686\/28-ans-apres-ce-jeu-video-playstation-compare-a-l-un-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne.htm\">En savoir plus<\/a>.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/image.jeuxvideo.com\/medias-lg\/174256\/1742560270-2039-card.jpg?w=1140&#038;ssl=1\" alt=\"Croc jeu vid\u00e9o\"><\/p>\n<p>#Croc #PlayStation #RetroGaming #JeuxVideo #90s<\/p>\n<p><\/p>\n<hr>\n<p><a href=\"https:\/\/eternos974.live\/index.php\/2025\/02\/15\/on-tape-sur-des-boss-a-la-mode-viking\/\">\ud83d\udd34 Retrouvez notre dernier article : ON TAPE SUR DES BOSS A LA MODE VIKING !<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le l\u00e9gendaire jeu vid\u00e9o de PlayStation, Croc, consid\u00e9r\u00e9 comme l&rsquo;un des meilleurs de tous les temps, fait un retour remarqu\u00e9&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[43,20],"tags":[44],"class_list":["post-5246","post","type-post","status-publish","format-aside","hentry","category-breve","category-news","tag-breve","post_format-post-format-aside"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Le l\u00e9gendaire jeu vid\u00e9o de PlayStation, Croc, consid\u00e9r\u00e9 comme l&#039;un des meilleurs de tous les temps, fait un retour remarqu\u00e9 apr\u00e8s 28 ans. Cette r\u00e9\u00e9dition du c\u00e9l\u00e8bre jeu des ann\u00e9es 90 s&#039;accompagne d&#039;une version ultra moderne, d&#039;une date de sortie et d&#039;un trailer in\u00e9dits. En savoir plus. #Croc #PlayStation #RetroGaming #JeuxVideo #90s \ud83d\udd34 Retrouvez notre\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"eternos974\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"L&#039;EternoStation - LIVE, CHILL &amp; FUN\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"28 ans apr\u00e8s, ce jeu vid\u00e9o PlayStation compar\u00e9 \u00e0 l\u2019un des meilleurs de tous les temps revient dans une version ultra moderne\u2026 - L&#039;EternoStation\" \/>\n\t\t<meta property=\"og:description\" content=\"Le l\u00e9gendaire jeu vid\u00e9o de PlayStation, Croc, consid\u00e9r\u00e9 comme l&#039;un des meilleurs de tous les temps, fait un retour remarqu\u00e9 apr\u00e8s 28 ans. Cette r\u00e9\u00e9dition du c\u00e9l\u00e8bre jeu des ann\u00e9es 90 s&#039;accompagne d&#039;une version ultra moderne, d&#039;une date de sortie et d&#039;un trailer in\u00e9dits. En savoir plus. #Croc #PlayStation #RetroGaming #JeuxVideo #90s \ud83d\udd34 Retrouvez notre\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-03-22T18:02:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-03-22T18:02:56+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"28 ans apr\u00e8s, ce jeu vid\u00e9o PlayStation compar\u00e9 \u00e0 l\u2019un des meilleurs de tous les temps revient dans une version ultra moderne\u2026 - L&#039;EternoStation\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Le l\u00e9gendaire jeu vid\u00e9o de PlayStation, Croc, consid\u00e9r\u00e9 comme l&#039;un des meilleurs de tous les temps, fait un retour remarqu\u00e9 apr\u00e8s 28 ans. Cette r\u00e9\u00e9dition du c\u00e9l\u00e8bre jeu des ann\u00e9es 90 s&#039;accompagne d&#039;une version ultra moderne, d&#039;une date de sortie et d&#039;un trailer in\u00e9dits. En savoir plus. #Croc #PlayStation #RetroGaming #JeuxVideo #90s \ud83d\udd34 Retrouvez notre\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/03\\\/22\\\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\\\/#blogposting\",\"name\":\"28 ans apr\\u00e8s, ce jeu vid\\u00e9o PlayStation compar\\u00e9 \\u00e0 l\\u2019un des meilleurs de tous les temps revient dans une version ultra moderne\\u2026 - L'EternoStation\",\"headline\":\"28 ans apr\\u00e8s, ce jeu vid\\u00e9o PlayStation compar\\u00e9 \\u00e0 l&rsquo;un des meilleurs de tous les temps revient dans une version ultra moderne&#8230;\",\"author\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/image.jeuxvideo.com\\\/medias-lg\\\/174256\\\/1742560270-2039-card.jpg\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/03\\\/22\\\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\\\/#articleImage\"},\"datePublished\":\"2025-03-22T22:02:56+04:00\",\"dateModified\":\"2025-03-22T22:02:56+04:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/03\\\/22\\\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/03\\\/22\\\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\\\/#webpage\"},\"articleSection\":\"br\\u00e8ve, news, br\\u00e8ve, En passant\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/03\\\/22\\\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live#listItem\",\"position\":1,\"name\":\"Domicile\",\"item\":\"https:\\\/\\\/eternos974.live\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"news\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"news\",\"item\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/breve\\\/#listItem\",\"name\":\"br\\u00e8ve\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live#listItem\",\"name\":\"Domicile\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/breve\\\/#listItem\",\"position\":3,\"name\":\"br\\u00e8ve\",\"item\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/breve\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/03\\\/22\\\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\\\/#listItem\",\"name\":\"28 ans apr\\u00e8s, ce jeu vid\\u00e9o PlayStation compar\\u00e9 \\u00e0 l&rsquo;un des meilleurs de tous les temps revient dans une version ultra moderne&#8230;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"news\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/03\\\/22\\\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\\\/#listItem\",\"position\":4,\"name\":\"28 ans apr\\u00e8s, ce jeu vid\\u00e9o PlayStation compar\\u00e9 \\u00e0 l&rsquo;un des meilleurs de tous les temps revient dans une version ultra moderne&#8230;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/breve\\\/#listItem\",\"name\":\"br\\u00e8ve\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/#organization\",\"name\":\"L'EternoStation\",\"description\":\"LIVE, CHILL & FUN\",\"url\":\"https:\\\/\\\/eternos974.live\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/#author\",\"url\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/\",\"name\":\"eternos974\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/03\\\/22\\\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7141af684a779babd9913ea86616250a147cbdf2bd354aa007f434fc4dc1aff?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"eternos974\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/03\\\/22\\\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\\\/#webpage\",\"url\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/03\\\/22\\\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\\\/\",\"name\":\"28 ans apr\\u00e8s, ce jeu vid\\u00e9o PlayStation compar\\u00e9 \\u00e0 l\\u2019un des meilleurs de tous les temps revient dans une version ultra moderne\\u2026 - L'EternoStation\",\"description\":\"Le l\\u00e9gendaire jeu vid\\u00e9o de PlayStation, Croc, consid\\u00e9r\\u00e9 comme l'un des meilleurs de tous les temps, fait un retour remarqu\\u00e9 apr\\u00e8s 28 ans. Cette r\\u00e9\\u00e9dition du c\\u00e9l\\u00e8bre jeu des ann\\u00e9es 90 s'accompagne d'une version ultra moderne, d'une date de sortie et d'un trailer in\\u00e9dits. En savoir plus. #Croc #PlayStation #RetroGaming #JeuxVideo #90s \\ud83d\\udd34 Retrouvez notre\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/03\\\/22\\\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/#author\"},\"datePublished\":\"2025-03-22T22:02:56+04:00\",\"dateModified\":\"2025-03-22T22:02:56+04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/#website\",\"url\":\"https:\\\/\\\/eternos974.live\\\/\",\"name\":\"L'EternoStation\",\"description\":\"LIVE, CHILL & FUN\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"28 ans apr\u00e8s, ce jeu vid\u00e9o PlayStation compar\u00e9 \u00e0 l\u2019un des meilleurs de tous les temps revient dans une version ultra moderne\u2026 - L'EternoStation","description":"Le l\u00e9gendaire jeu vid\u00e9o de PlayStation, Croc, consid\u00e9r\u00e9 comme l'un des meilleurs de tous les temps, fait un retour remarqu\u00e9 apr\u00e8s 28 ans. Cette r\u00e9\u00e9dition du c\u00e9l\u00e8bre jeu des ann\u00e9es 90 s'accompagne d'une version ultra moderne, d'une date de sortie et d'un trailer in\u00e9dits. En savoir plus. #Croc #PlayStation #RetroGaming #JeuxVideo #90s \ud83d\udd34 Retrouvez notre","canonical_url":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/#blogposting","name":"28 ans apr\u00e8s, ce jeu vid\u00e9o PlayStation compar\u00e9 \u00e0 l\u2019un des meilleurs de tous les temps revient dans une version ultra moderne\u2026 - L'EternoStation","headline":"28 ans apr\u00e8s, ce jeu vid\u00e9o PlayStation compar\u00e9 \u00e0 l&rsquo;un des meilleurs de tous les temps revient dans une version ultra moderne&#8230;","author":{"@id":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/#author"},"publisher":{"@id":"https:\/\/eternos974.live\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/image.jeuxvideo.com\/medias-lg\/174256\/1742560270-2039-card.jpg","@id":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/#articleImage"},"datePublished":"2025-03-22T22:02:56+04:00","dateModified":"2025-03-22T22:02:56+04:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/#webpage"},"isPartOf":{"@id":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/#webpage"},"articleSection":"br\u00e8ve, news, br\u00e8ve, En passant"},{"@type":"BreadcrumbList","@id":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eternos974.live#listItem","position":1,"name":"Domicile","item":"https:\/\/eternos974.live","nextItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/#listItem","name":"news"}},{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/#listItem","position":2,"name":"news","item":"https:\/\/eternos974.live\/index.php\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/#listItem","name":"br\u00e8ve"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live#listItem","name":"Domicile"}},{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/#listItem","position":3,"name":"br\u00e8ve","item":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/#listItem","name":"28 ans apr\u00e8s, ce jeu vid\u00e9o PlayStation compar\u00e9 \u00e0 l&rsquo;un des meilleurs de tous les temps revient dans une version ultra moderne&#8230;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/#listItem","name":"news"}},{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/#listItem","position":4,"name":"28 ans apr\u00e8s, ce jeu vid\u00e9o PlayStation compar\u00e9 \u00e0 l&rsquo;un des meilleurs de tous les temps revient dans une version ultra moderne&#8230;","previousItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/#listItem","name":"br\u00e8ve"}}]},{"@type":"Organization","@id":"https:\/\/eternos974.live\/#organization","name":"L'EternoStation","description":"LIVE, CHILL & FUN","url":"https:\/\/eternos974.live\/"},{"@type":"Person","@id":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/#author","url":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/","name":"eternos974","image":{"@type":"ImageObject","@id":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f7141af684a779babd9913ea86616250a147cbdf2bd354aa007f434fc4dc1aff?s=96&d=mm&r=g","width":96,"height":96,"caption":"eternos974"}},{"@type":"WebPage","@id":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/#webpage","url":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/","name":"28 ans apr\u00e8s, ce jeu vid\u00e9o PlayStation compar\u00e9 \u00e0 l\u2019un des meilleurs de tous les temps revient dans une version ultra moderne\u2026 - L'EternoStation","description":"Le l\u00e9gendaire jeu vid\u00e9o de PlayStation, Croc, consid\u00e9r\u00e9 comme l'un des meilleurs de tous les temps, fait un retour remarqu\u00e9 apr\u00e8s 28 ans. Cette r\u00e9\u00e9dition du c\u00e9l\u00e8bre jeu des ann\u00e9es 90 s'accompagne d'une version ultra moderne, d'une date de sortie et d'un trailer in\u00e9dits. En savoir plus. #Croc #PlayStation #RetroGaming #JeuxVideo #90s \ud83d\udd34 Retrouvez notre","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/eternos974.live\/#website"},"breadcrumb":{"@id":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/#breadcrumblist"},"author":{"@id":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/#author"},"creator":{"@id":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/#author"},"datePublished":"2025-03-22T22:02:56+04:00","dateModified":"2025-03-22T22:02:56+04:00"},{"@type":"WebSite","@id":"https:\/\/eternos974.live\/#website","url":"https:\/\/eternos974.live\/","name":"L'EternoStation","description":"LIVE, CHILL & FUN","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/eternos974.live\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"L'EternoStation - LIVE, CHILL &amp; FUN","og:type":"article","og:title":"28 ans apr\u00e8s, ce jeu vid\u00e9o PlayStation compar\u00e9 \u00e0 l\u2019un des meilleurs de tous les temps revient dans une version ultra moderne\u2026 - L'EternoStation","og:description":"Le l\u00e9gendaire jeu vid\u00e9o de PlayStation, Croc, consid\u00e9r\u00e9 comme l'un des meilleurs de tous les temps, fait un retour remarqu\u00e9 apr\u00e8s 28 ans. Cette r\u00e9\u00e9dition du c\u00e9l\u00e8bre jeu des ann\u00e9es 90 s'accompagne d'une version ultra moderne, d'une date de sortie et d'un trailer in\u00e9dits. En savoir plus. #Croc #PlayStation #RetroGaming #JeuxVideo #90s \ud83d\udd34 Retrouvez notre","og:url":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/","article:published_time":"2025-03-22T18:02:56+00:00","article:modified_time":"2025-03-22T18:02:56+00:00","twitter:card":"summary_large_image","twitter:title":"28 ans apr\u00e8s, ce jeu vid\u00e9o PlayStation compar\u00e9 \u00e0 l\u2019un des meilleurs de tous les temps revient dans une version ultra moderne\u2026 - L'EternoStation","twitter:description":"Le l\u00e9gendaire jeu vid\u00e9o de PlayStation, Croc, consid\u00e9r\u00e9 comme l'un des meilleurs de tous les temps, fait un retour remarqu\u00e9 apr\u00e8s 28 ans. Cette r\u00e9\u00e9dition du c\u00e9l\u00e8bre jeu des ann\u00e9es 90 s'accompagne d'une version ultra moderne, d'une date de sortie et d'un trailer in\u00e9dits. En savoir plus. #Croc #PlayStation #RetroGaming #JeuxVideo #90s \ud83d\udd34 Retrouvez notre"},"aioseo_meta_data":{"post_id":"5246","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-03-22 18:11:24","updated":"2025-06-08 16:29:10","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eternos974.live\" title=\"Domicile\">Domicile<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eternos974.live\/index.php\/category\/news\/\" title=\"news\">news<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/\" title=\"br\u00e8ve\">br\u00e8ve<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t28 ans apr\u00e8s, ce jeu vid\u00e9o PlayStation compar\u00e9 \u00e0 l\u2019un des meilleurs de tous les temps revient dans une version ultra moderne\u2026\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Domicile","link":"https:\/\/eternos974.live"},{"label":"news","link":"https:\/\/eternos974.live\/index.php\/category\/news\/"},{"label":"br\u00e8ve","link":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/"},{"label":"28 ans apr\u00e8s, ce jeu vid\u00e9o PlayStation compar\u00e9 \u00e0 l&rsquo;un des meilleurs de tous les temps revient dans une version ultra moderne&#8230;","link":"https:\/\/eternos974.live\/index.php\/2025\/03\/22\/28-ans-apres-ce-jeu-video-playstation-compare-a-lun-des-meilleurs-de-tous-les-temps-revient-dans-une-version-ultra-moderne\/"}],"jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts\/5246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/comments?post=5246"}],"version-history":[{"count":1,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts\/5246\/revisions"}],"predecessor-version":[{"id":5247,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts\/5246\/revisions\/5247"}],"wp:attachment":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/media?parent=5246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/categories?post=5246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/tags?post=5246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}