{"id":8426,"date":"2025-06-26T15:35:06","date_gmt":"2025-06-26T11:35:06","guid":{"rendered":"https:\/\/eternos974.live\/?p=8426"},"modified":"2025-06-26T15:35:06","modified_gmt":"2025-06-26T11:35:06","slug":"superman-apres-la-controverse-james-gunn-rassure-les-spectateurs","status":"publish","type":"post","link":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/","title":{"rendered":"Superman\u00a0: apr\u00e8s la controverse, James Gunn rassure les spectateurs"},"content":{"rendered":"<p>La sc\u00e8ne controvers\u00e9e de <a href=\"https:\/\/www.journaldugeek.com\/2025\/06\/24\/apres-la-controverse-james-gunn-rassure-les-spectateurs\/\">Superman<\/a> qui a fait d\u00e9bat sur les r\u00e9seaux sociaux n&rsquo;apparaitra finalement pas sur le montage final, rassure James Gunn. Le public semble avoir eu gain de cause. <\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.journaldugeek.com\/app\/uploads\/2025\/06\/superman-plan-controverse.jpg?resize=1140%2C760&#038;ssl=1\" alt=\"Superman controversy\" width=\"1140\" height=\"760\"><\/p>\n<p>#Superman #JamesGunn #ControversyResolved<\/p>\n<p><\/p>\n<hr>\n<p><a href=\"https:\/\/eternos974.live\/index.php\/2025\/06\/18\/decouverte-de-kiborg-un-beatem-up-rogue-lite-explosif\/\">\ud83d\udd34 Retrouvez notre dernier article : D\u00e9couverte de KIBORG : Un Beat&#8217;em Up Rogue-Lite Explosif<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sc\u00e8ne controvers\u00e9e de Superman qui a fait d\u00e9bat sur les r\u00e9seaux sociaux n&rsquo;apparaitra finalement pas sur le montage final,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[43,20],"tags":[44],"class_list":["post-8426","post","type-post","status-publish","format-aside","hentry","category-breve","category-news","tag-breve","post_format-post-format-aside"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La sc\u00e8ne controvers\u00e9e de Superman qui a fait d\u00e9bat sur les r\u00e9seaux sociaux n&#039;apparaitra finalement pas sur le montage final, rassure James Gunn. Le public semble avoir eu gain de cause. #Superman #JamesGunn #ControversyResolved \ud83d\udd34 Retrouvez notre dernier article : D\u00e9couverte de KIBORG : Un Beat&#039;em Up Rogue-Lite Explosif\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"eternos974\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"L&#039;EternoStation - LIVE, CHILL &amp; FUN\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Superman : apr\u00e8s la controverse, James Gunn rassure les spectateurs - L&#039;EternoStation\" \/>\n\t\t<meta property=\"og:description\" content=\"La sc\u00e8ne controvers\u00e9e de Superman qui a fait d\u00e9bat sur les r\u00e9seaux sociaux n&#039;apparaitra finalement pas sur le montage final, rassure James Gunn. Le public semble avoir eu gain de cause. #Superman #JamesGunn #ControversyResolved \ud83d\udd34 Retrouvez notre dernier article : D\u00e9couverte de KIBORG : Un Beat&#039;em Up Rogue-Lite Explosif\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-06-26T11:35:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-06-26T11:35:06+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Superman : apr\u00e8s la controverse, James Gunn rassure les spectateurs - L&#039;EternoStation\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La sc\u00e8ne controvers\u00e9e de Superman qui a fait d\u00e9bat sur les r\u00e9seaux sociaux n&#039;apparaitra finalement pas sur le montage final, rassure James Gunn. Le public semble avoir eu gain de cause. #Superman #JamesGunn #ControversyResolved \ud83d\udd34 Retrouvez notre dernier article : D\u00e9couverte de KIBORG : Un Beat&#039;em Up Rogue-Lite Explosif\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/06\\\/26\\\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\\\/#blogposting\",\"name\":\"Superman : apr\\u00e8s la controverse, James Gunn rassure les spectateurs - L'EternoStation\",\"headline\":\"Superman\\u00a0: apr\\u00e8s la controverse, James Gunn rassure les spectateurs\",\"author\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.journaldugeek.com\\\/app\\\/uploads\\\/2025\\\/06\\\/superman-plan-controverse.jpg\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/06\\\/26\\\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\\\/#articleImage\"},\"datePublished\":\"2025-06-26T15:35:06+04:00\",\"dateModified\":\"2025-06-26T15:35:06+04:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/06\\\/26\\\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/06\\\/26\\\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\\\/#webpage\"},\"articleSection\":\"br\\u00e8ve, news, br\\u00e8ve, En passant\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/06\\\/26\\\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live#listItem\",\"position\":1,\"name\":\"Domicile\",\"item\":\"https:\\\/\\\/eternos974.live\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"news\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"news\",\"item\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/breve\\\/#listItem\",\"name\":\"br\\u00e8ve\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live#listItem\",\"name\":\"Domicile\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/breve\\\/#listItem\",\"position\":3,\"name\":\"br\\u00e8ve\",\"item\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/breve\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/06\\\/26\\\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\\\/#listItem\",\"name\":\"Superman\\u00a0: apr\\u00e8s la controverse, James Gunn rassure les spectateurs\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"news\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/06\\\/26\\\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\\\/#listItem\",\"position\":4,\"name\":\"Superman\\u00a0: apr\\u00e8s la controverse, James Gunn rassure les spectateurs\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/category\\\/news\\\/breve\\\/#listItem\",\"name\":\"br\\u00e8ve\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/#organization\",\"name\":\"L'EternoStation\",\"description\":\"LIVE, CHILL & FUN\",\"url\":\"https:\\\/\\\/eternos974.live\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/#author\",\"url\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/\",\"name\":\"eternos974\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/06\\\/26\\\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7141af684a779babd9913ea86616250a147cbdf2bd354aa007f434fc4dc1aff?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"eternos974\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/06\\\/26\\\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\\\/#webpage\",\"url\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/06\\\/26\\\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\\\/\",\"name\":\"Superman : apr\\u00e8s la controverse, James Gunn rassure les spectateurs - L'EternoStation\",\"description\":\"La sc\\u00e8ne controvers\\u00e9e de Superman qui a fait d\\u00e9bat sur les r\\u00e9seaux sociaux n'apparaitra finalement pas sur le montage final, rassure James Gunn. Le public semble avoir eu gain de cause. #Superman #JamesGunn #ControversyResolved \\ud83d\\udd34 Retrouvez notre dernier article : D\\u00e9couverte de KIBORG : Un Beat'em Up Rogue-Lite Explosif\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/2025\\\/06\\\/26\\\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/index.php\\\/author\\\/eternos974\\\/#author\"},\"datePublished\":\"2025-06-26T15:35:06+04:00\",\"dateModified\":\"2025-06-26T15:35:06+04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eternos974.live\\\/#website\",\"url\":\"https:\\\/\\\/eternos974.live\\\/\",\"name\":\"L'EternoStation\",\"description\":\"LIVE, CHILL & FUN\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/eternos974.live\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Superman : apr\u00e8s la controverse, James Gunn rassure les spectateurs - L'EternoStation","description":"La sc\u00e8ne controvers\u00e9e de Superman qui a fait d\u00e9bat sur les r\u00e9seaux sociaux n'apparaitra finalement pas sur le montage final, rassure James Gunn. Le public semble avoir eu gain de cause. #Superman #JamesGunn #ControversyResolved \ud83d\udd34 Retrouvez notre dernier article : D\u00e9couverte de KIBORG : Un Beat'em Up Rogue-Lite Explosif","canonical_url":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/#blogposting","name":"Superman : apr\u00e8s la controverse, James Gunn rassure les spectateurs - L'EternoStation","headline":"Superman\u00a0: apr\u00e8s la controverse, James Gunn rassure les spectateurs","author":{"@id":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/#author"},"publisher":{"@id":"https:\/\/eternos974.live\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.journaldugeek.com\/app\/uploads\/2025\/06\/superman-plan-controverse.jpg","@id":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/#articleImage"},"datePublished":"2025-06-26T15:35:06+04:00","dateModified":"2025-06-26T15:35:06+04:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/#webpage"},"isPartOf":{"@id":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/#webpage"},"articleSection":"br\u00e8ve, news, br\u00e8ve, En passant"},{"@type":"BreadcrumbList","@id":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eternos974.live#listItem","position":1,"name":"Domicile","item":"https:\/\/eternos974.live","nextItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/#listItem","name":"news"}},{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/#listItem","position":2,"name":"news","item":"https:\/\/eternos974.live\/index.php\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/#listItem","name":"br\u00e8ve"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live#listItem","name":"Domicile"}},{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/#listItem","position":3,"name":"br\u00e8ve","item":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/#listItem","name":"Superman\u00a0: apr\u00e8s la controverse, James Gunn rassure les spectateurs"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/#listItem","name":"news"}},{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/#listItem","position":4,"name":"Superman\u00a0: apr\u00e8s la controverse, James Gunn rassure les spectateurs","previousItem":{"@type":"ListItem","@id":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/#listItem","name":"br\u00e8ve"}}]},{"@type":"Organization","@id":"https:\/\/eternos974.live\/#organization","name":"L'EternoStation","description":"LIVE, CHILL & FUN","url":"https:\/\/eternos974.live\/"},{"@type":"Person","@id":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/#author","url":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/","name":"eternos974","image":{"@type":"ImageObject","@id":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f7141af684a779babd9913ea86616250a147cbdf2bd354aa007f434fc4dc1aff?s=96&d=mm&r=g","width":96,"height":96,"caption":"eternos974"}},{"@type":"WebPage","@id":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/#webpage","url":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/","name":"Superman : apr\u00e8s la controverse, James Gunn rassure les spectateurs - L'EternoStation","description":"La sc\u00e8ne controvers\u00e9e de Superman qui a fait d\u00e9bat sur les r\u00e9seaux sociaux n'apparaitra finalement pas sur le montage final, rassure James Gunn. Le public semble avoir eu gain de cause. #Superman #JamesGunn #ControversyResolved \ud83d\udd34 Retrouvez notre dernier article : D\u00e9couverte de KIBORG : Un Beat'em Up Rogue-Lite Explosif","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/eternos974.live\/#website"},"breadcrumb":{"@id":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/#breadcrumblist"},"author":{"@id":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/#author"},"creator":{"@id":"https:\/\/eternos974.live\/index.php\/author\/eternos974\/#author"},"datePublished":"2025-06-26T15:35:06+04:00","dateModified":"2025-06-26T15:35:06+04:00"},{"@type":"WebSite","@id":"https:\/\/eternos974.live\/#website","url":"https:\/\/eternos974.live\/","name":"L'EternoStation","description":"LIVE, CHILL & FUN","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/eternos974.live\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"L'EternoStation - LIVE, CHILL &amp; FUN","og:type":"article","og:title":"Superman : apr\u00e8s la controverse, James Gunn rassure les spectateurs - L'EternoStation","og:description":"La sc\u00e8ne controvers\u00e9e de Superman qui a fait d\u00e9bat sur les r\u00e9seaux sociaux n'apparaitra finalement pas sur le montage final, rassure James Gunn. Le public semble avoir eu gain de cause. #Superman #JamesGunn #ControversyResolved \ud83d\udd34 Retrouvez notre dernier article : D\u00e9couverte de KIBORG : Un Beat'em Up Rogue-Lite Explosif","og:url":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/","article:published_time":"2025-06-26T11:35:06+00:00","article:modified_time":"2025-06-26T11:35:06+00:00","twitter:card":"summary_large_image","twitter:title":"Superman : apr\u00e8s la controverse, James Gunn rassure les spectateurs - L'EternoStation","twitter:description":"La sc\u00e8ne controvers\u00e9e de Superman qui a fait d\u00e9bat sur les r\u00e9seaux sociaux n'apparaitra finalement pas sur le montage final, rassure James Gunn. Le public semble avoir eu gain de cause. #Superman #JamesGunn #ControversyResolved \ud83d\udd34 Retrouvez notre dernier article : D\u00e9couverte de KIBORG : Un Beat'em Up Rogue-Lite Explosif"},"aioseo_meta_data":{"post_id":"8426","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-06-26 11:46:25","updated":"2025-06-26 11:46:25","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eternos974.live\" title=\"Domicile\">Domicile<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eternos974.live\/index.php\/category\/news\/\" title=\"news\">news<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/\" title=\"br\u00e8ve\">br\u00e8ve<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSuperman : apr\u00e8s la controverse, James Gunn rassure les spectateurs\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Domicile","link":"https:\/\/eternos974.live"},{"label":"news","link":"https:\/\/eternos974.live\/index.php\/category\/news\/"},{"label":"br\u00e8ve","link":"https:\/\/eternos974.live\/index.php\/category\/news\/breve\/"},{"label":"Superman\u00a0: apr\u00e8s la controverse, James Gunn rassure les spectateurs","link":"https:\/\/eternos974.live\/index.php\/2025\/06\/26\/superman-apres-la-controverse-james-gunn-rassure-les-spectateurs\/"}],"jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts\/8426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/comments?post=8426"}],"version-history":[{"count":1,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts\/8426\/revisions"}],"predecessor-version":[{"id":8427,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/posts\/8426\/revisions\/8427"}],"wp:attachment":[{"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/media?parent=8426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/categories?post=8426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eternos974.live\/index.php\/wp-json\/wp\/v2\/tags?post=8426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}